{"id":1389,"date":"2017-10-02T13:18:37","date_gmt":"2017-10-02T16:18:37","guid":{"rendered":"https:\/\/laurapitluk.com.ar\/wps\/?p=1389"},"modified":"2017-10-02T13:19:43","modified_gmt":"2017-10-02T16:19:43","slug":"expo-papeleria-y-omep","status":"publish","type":"post","link":"https:\/\/laurapitluk.com.ar\/wps\/expo-papeleria-y-omep\/","title":{"rendered":"Expo Papeler\u00eda y OMEP"},"content":{"rendered":"<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"left\">\n<div>\n<p><strong>El maestro Carlos Gianni&nbsp;<\/strong><strong>cerrar\u00e1 las Jornadas Docentes&nbsp;<\/strong><strong>con un taller l\u00fadico y musical<\/strong><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"left\">\n<div>\n<p>El espacio de aprendizaje y capacitaci\u00f3n para docentes de Expopapeler\u00eda se dar\u00e1 el gusto de tener este a\u00f1o al gran maestro Carlos Gianni al frente del \u00faltimo taller de las 9nas Jornadas que se har\u00e1n en paralelo con la expo. El jueves 5, desde las 19, el compositor de las obras que m\u00e1s inspiraron al teatro infantil y que marcaron a muchas generaciones de alumnos -y tambi\u00e9n maestros- llegar\u00e1 con una propuesta pensada especialmente con juegos y canciones para compartir en el auditorio.<\/p>\n<p>\u201cVamos a usar algo de papeles y los vamos a unir con textos de canciones y mucha m\u00fasica, tambi\u00e9n vamos a jugar con consignas y vamos a estar cantando P\u00e1jaro de Papel, una canci\u00f3n que habla de alas propias y sobre la libertad\u201d, cont\u00f3 a CIAL Docentes el autor de la m\u00fasica de las obras m\u00e1s recordadas de Hugo Mid\u00f3n, como los cl\u00e1sicos \u201cVivitos y coleando\u201d, \u201cLocos ReCuerdos\u201d, \u201cDerechos torcidos\u201d o \u201cHuesito Carac\u00fa\u201d, entre muchos otros.<\/p>\n<p>El taller sumar\u00e1 adem\u00e1s a Fabian Suigo, otro de los valiosos nombres del teatro y la cultura infantil. La actividad se desplegar\u00e1 en la Plaza de las Artes, dentro del pabell\u00f3n 1 de Costa Salguero, y el ingreso y la participaci\u00f3n es gratuita pero con inscripci\u00f3n previa (se puede hacer hasta el domingo en la p\u00e1gina&nbsp;<a href=\"http:\/\/www.expopapeleria.com.ar\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/www.expopapeleria.com.ar&amp;source=gmail&amp;ust=1507047168878000&amp;usg=AFQjCNGWI7vOFQr6m4Cjw3DW7_nMGkMT-w\">www.expopapeleria.com.a<wbr>r<\/a>) y solo para mayores de 18 a\u00f1os.<\/p>\n<p style=\"text-align: center;\">Sumate tambi\u00e9n a nuestro Instagram, buscanos ah\u00ed como cialexpopapeleria y compart\u00ed fotos y videos con&nbsp;#expopapeleria&nbsp;\u00a1Te esperamos!<br \/>\n&nbsp;\u2014 con&nbsp;Expo Papeler\u00eda&nbsp;y&nbsp;OMEP Argentina.&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-1390\" src=\"https:\/\/laurapitluk.com.ar\/wps\/wp-content\/uploads\/2017\/10\/omep.jpg\" alt=\"\" width=\"600\" height=\"639\" srcset=\"https:\/\/laurapitluk.com.ar\/wps\/wp-content\/uploads\/2017\/10\/omep.jpg 600w, https:\/\/laurapitluk.com.ar\/wps\/wp-content\/uploads\/2017\/10\/omep-282x300.jpg 282w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El maestro Carlos Gianni&nbsp;cerrar\u00e1 las Jornadas Docentes&nbsp;con un taller l\u00fadico y musical El espacio de aprendizaje y capacitaci\u00f3n para docentes&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":1390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[29],"tags":[],"_links":{"self":[{"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/posts\/1389"}],"collection":[{"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/comments?post=1389"}],"version-history":[{"count":1,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/posts\/1389\/revisions"}],"predecessor-version":[{"id":1391,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/posts\/1389\/revisions\/1391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/media?parent=1389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/categories?post=1389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurapitluk.com.ar\/wps\/wp-json\/wp\/v2\/tags?post=1389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}